{"id":2337,"date":"2018-09-13T12:59:41","date_gmt":"2018-09-13T10:59:41","guid":{"rendered":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3.jpg"},"modified":"2018-09-13T13:00:18","modified_gmt":"2018-09-13T11:00:18","slug":"pk_redloungespectrums3-2","status":"inherit","type":"attachment","link":"https:\/\/willybrandtcenter.org\/en\/de\/pk_redloungespectrums3-2\/","title":{"rendered":"PK_RedLoungeSpectrums3"},"author":3,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PK_RedLoungeSpectrums3 - Willy Brandt Center Jerusalem<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3.jpg\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PK_RedLoungeSpectrums3 - Willy Brandt Center Jerusalem\" \/>\n<meta property=\"og:url\" content=\"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Willy Brandt Center Jerusalem\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-13T11:00:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/willybrandtcenter.org\/en\/en\/#website\",\"url\":\"https:\/\/willybrandtcenter.org\/en\/en\/\",\"name\":\"Willy Brandt Center Jerusalem\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/willybrandtcenter.org\/en\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3.jpg#webpage\",\"url\":\"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3.jpg\",\"name\":\"PK_RedLoungeSpectrums3 - Willy Brandt Center Jerusalem\",\"isPartOf\":{\"@id\":\"https:\/\/willybrandtcenter.org\/en\/en\/#website\"},\"datePublished\":\"2018-09-13T10:59:41+00:00\",\"dateModified\":\"2018-09-13T11:00:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3.jpg#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/willybrandtcenter.org\/en\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PK_RedLoungeSpectrums3\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PK_RedLoungeSpectrums3 - Willy Brandt Center Jerusalem","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3.jpg","og_locale":"de_DE","og_type":"article","og_title":"PK_RedLoungeSpectrums3 - Willy Brandt Center Jerusalem","og_url":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3.jpg","og_site_name":"Willy Brandt Center Jerusalem","article_modified_time":"2018-09-13T11:00:18+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3.jpg","type":"image\/jpeg"}],"twitter_card":"summary","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/willybrandtcenter.org\/en\/en\/#website","url":"https:\/\/willybrandtcenter.org\/en\/en\/","name":"Willy Brandt Center Jerusalem","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/willybrandtcenter.org\/en\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3.jpg#webpage","url":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3.jpg","name":"PK_RedLoungeSpectrums3 - Willy Brandt Center Jerusalem","isPartOf":{"@id":"https:\/\/willybrandtcenter.org\/en\/en\/#website"},"datePublished":"2018-09-13T10:59:41+00:00","dateModified":"2018-09-13T11:00:18+00:00","breadcrumb":{"@id":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3.jpg#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/willybrandtcenter.org\/en\/de\/"},{"@type":"ListItem","position":2,"name":"PK_RedLoungeSpectrums3"}]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3.jpg'><img width=\"300\" height=\"225\" src=\"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3-300x225.jpg\" class=\"avia-img-lazy-loading-2337 attachment-medium size-medium\" alt=\"\" loading=\"lazy\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1280,"height":960,"file":"2018\/09\/PK_RedLoungeSpectrums3.jpg","sizes":{"thumbnail":{"file":"PK_RedLoungeSpectrums3-80x80.jpg","width":80,"height":80,"mime_type":"image\/jpeg","source_url":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3-80x80.jpg"},"medium":{"file":"PK_RedLoungeSpectrums3-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3-300x225.jpg"},"medium_large":{"file":"PK_RedLoungeSpectrums3-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3-768x576.jpg"},"large":{"file":"PK_RedLoungeSpectrums3-1030x773.jpg","width":1030,"height":773,"mime_type":"image\/jpeg","source_url":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3-1030x773.jpg"},"widget":{"file":"PK_RedLoungeSpectrums3-36x36.jpg","width":36,"height":36,"mime_type":"image\/jpeg","source_url":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3-36x36.jpg"},"square":{"file":"PK_RedLoungeSpectrums3-180x180.jpg","width":180,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3-180x180.jpg"},"featured":{"file":"PK_RedLoungeSpectrums3-1280x430.jpg","width":1280,"height":430,"mime_type":"image\/jpeg","source_url":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3-1280x430.jpg"},"featured_large":{"file":"PK_RedLoungeSpectrums3-1280x630.jpg","width":1280,"height":630,"mime_type":"image\/jpeg","source_url":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3-1280x630.jpg"},"portfolio":{"file":"PK_RedLoungeSpectrums3-495x400.jpg","width":495,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3-495x400.jpg"},"portfolio_small":{"file":"PK_RedLoungeSpectrums3-260x185.jpg","width":260,"height":185,"mime_type":"image\/jpeg","source_url":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3-260x185.jpg"},"gallery":{"file":"PK_RedLoungeSpectrums3-845x684.jpg","width":845,"height":684,"mime_type":"image\/jpeg","source_url":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3-845x684.jpg"},"magazine":{"file":"PK_RedLoungeSpectrums3-710x375.jpg","width":710,"height":375,"mime_type":"image\/jpeg","source_url":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3-710x375.jpg"},"masonry":{"file":"PK_RedLoungeSpectrums3-705x529.jpg","width":705,"height":529,"mime_type":"image\/jpeg","source_url":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3-705x529.jpg"},"entry_with_sidebar":{"file":"PK_RedLoungeSpectrums3-845x321.jpg","width":845,"height":321,"mime_type":"image\/jpeg","source_url":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3-845x321.jpg"},"entry_without_sidebar":{"file":"PK_RedLoungeSpectrums3-1210x423.jpg","width":1210,"height":423,"mime_type":"image\/jpeg","source_url":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3-1210x423.jpg"},"shop_thumbnail":{"file":"PK_RedLoungeSpectrums3-120x120.jpg","width":120,"height":120,"mime_type":"image\/jpeg","source_url":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3-120x120.jpg"},"shop_catalog":{"file":"PK_RedLoungeSpectrums3-450x450.jpg","width":450,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3-450x450.jpg"},"shop_single":{"file":"PK_RedLoungeSpectrums3-450x338.jpg","width":450,"height":338,"mime_type":"image\/jpeg","source_url":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3-450x338.jpg"},"full":{"file":"PK_RedLoungeSpectrums3.jpg","width":1280,"height":960,"mime_type":"image\/jpeg","source_url":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/willybrandtcenter.org\/wp-content\/uploads\/2018\/09\/PK_RedLoungeSpectrums3.jpg","_links":{"self":[{"href":"https:\/\/willybrandtcenter.org\/en\/de\/wp-json\/wp\/v2\/media\/2337\/"}],"collection":[{"href":"https:\/\/willybrandtcenter.org\/en\/de\/wp-json\/wp\/v2\/media\/"}],"about":[{"href":"https:\/\/willybrandtcenter.org\/en\/de\/wp-json\/wp\/v2\/types\/attachment\/"}],"author":[{"embeddable":true,"href":"https:\/\/willybrandtcenter.org\/en\/de\/wp-json\/wp\/v2\/users\/3\/"}],"replies":[{"embeddable":true,"href":"https:\/\/willybrandtcenter.org\/en\/de\/wp-json\/wp\/v2\/comments\/?post=2337"}]}}